{"id":605,"count":1,"description":"","link":"https:\/\/gestconocimiento.org\/xiv-congreso\/ponentes\/camilo-molina-guerrero\/","name":"Camilo Molina Guerrero","slug":"camilo-molina-guerrero","taxonomy":"ponentes","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/gestconocimiento.org\/xiv-congreso\/wp-json\/wp\/v2\/ponentes\/605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gestconocimiento.org\/xiv-congreso\/wp-json\/wp\/v2\/ponentes"}],"about":[{"href":"https:\/\/gestconocimiento.org\/xiv-congreso\/wp-json\/wp\/v2\/taxonomies\/ponentes"}]}}