{"id":591,"count":1,"description":"","link":"https:\/\/gestconocimiento.org\/xiv-congreso\/ponentes\/luz-angela-leon-blanco-2\/","name":"Luz Angela Leon Blanco","slug":"luz-angela-leon-blanco-2","taxonomy":"ponentes","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/gestconocimiento.org\/xiv-congreso\/wp-json\/wp\/v2\/ponentes\/591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gestconocimiento.org\/xiv-congreso\/wp-json\/wp\/v2\/ponentes"}],"about":[{"href":"https:\/\/gestconocimiento.org\/xiv-congreso\/wp-json\/wp\/v2\/taxonomies\/ponentes"}]}}